{"id":3,"date":"2025-03-10T18:17:00","date_gmt":"2025-03-10T17:17:00","guid":{"rendered":"https:\/\/www.avvocatomazzulloacquepubbliche.com\/?page_id=3"},"modified":"2025-06-16T23:33:32","modified_gmt":"2025-06-16T21:33:32","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/oceanoblunonsolointimo.it\/index.php\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; theme_builder_area=&#8221;post_content&#8221; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Chi siamo<\/h2>\n<!-- \/wp:heading -->\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>L'indirizzo del nostro sito web \u00e8: https:\/\/www.avvocatomazzulloacquepubbliche.com.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Commenti<\/h2>\n<!-- \/wp:heading -->\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Quando i visitatori lasciano commenti sul sito, raccogliamo i dati mostrati nel modulo dei commenti oltre all'indirizzo IP del visitatore e la stringa dello user agent del browser per facilitare il rilevamento dello spam.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:paragraph -->\n<p>Una stringa anonimizzata creata a partire dal tuo indirizzo email (altrimenti detta hash) pu\u00f2 essere fornita al servizio Gravatar per vedere se lo stai usando. La privacy policy del servizio Gravatar \u00e8 disponibile qui: https:\/\/automattic.com\/privacy\/. Dopo l'approvazione del tuo commento, la tua immagine del profilo \u00e8 visibile al pubblico nel contesto del tuo commento.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Media<\/h2>\n<!-- \/wp:heading -->\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Se carichi immagini sul sito web, dovresti evitare di caricare immagini che includono i dati di posizione incorporati (EXIF GPS). I visitatori del sito web possono scaricare ed estrarre qualsiasi dato sulla posizione dalle immagini sul sito web.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Cookie<\/h2>\n<!-- \/wp:heading -->\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Se lasci un commento sul nostro sito, puoi scegliere di salvare il tuo nome, indirizzo email e sito web nei cookie. Sono usati per la tua comodit\u00e0 in modo che tu non debba inserire nuovamente i tuoi dati quando lasci un altro commento. Questi cookie dureranno per un anno.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:paragraph -->\n<p>Se visiti la pagina di login, verr\u00e0 impostato un cookie temporaneo per determinare se il tuo browser accetta i cookie. Questo cookie non contiene dati personali e viene eliminato quando chiudi il browser.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:paragraph -->\n<p>Quando effettui l'accesso, verranno impostati diversi cookie per salvare le tue informazioni di accesso e le tue opzioni di visualizzazione dello schermo. I cookie di accesso durano due giorni mentre i cookie per le opzioni dello schermo durano un anno. Se selezioni &quot;Ricordami&quot;, il tuo accesso persister\u00e0 per due settimane. Se esci dal tuo account, i cookie di accesso verranno rimossi.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:paragraph -->\n<p>Se modifichi o pubblichi un articolo, un cookie aggiuntivo verr\u00e0 salvato nel tuo browser. Questo cookie non include dati personali, ma indica semplicemente l'ID dell'articolo appena modificato. Scade dopo 1 giorno.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Contenuto incorporato da altri siti web<\/h2>\n<!-- \/wp:heading -->\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Gli articoli su questo sito possono includere contenuti incorporati (ad esempio video, immagini, articoli, ecc.). I contenuti incorporati da altri siti web si comportano esattamente allo stesso modo come se il visitatore avesse visitato l'altro sito web.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:paragraph -->\n<p>Questi siti web possono raccogliere dati su di te, usare cookie, integrare ulteriori tracciamenti di terze parti e monitorare l'interazione con essi, incluso il tracciamento della tua interazione con il contenuto incorporato se hai un account e sei connesso a quei siti web.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Con chi condividiamo i tuoi dati<\/h2>\n<!-- \/wp:heading -->\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Se richiedi una reimpostazione della password, il tuo indirizzo IP verr\u00e0 incluso nell'email di reimpostazione.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Per quanto tempo conserviamo i tuoi dati<\/h2>\n<!-- \/wp:heading -->\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Se lasci un commento, il commento e i relativi metadati vengono conservati a tempo indeterminato. \u00c8 cos\u00ec che possiamo riconoscere e approvare automaticamente eventuali commenti successivi invece di tenerli in una coda di moderazione.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:paragraph -->\n<p>Per gli utenti che si registrano sul nostro sito web (se presenti), memorizziamo anche le informazioni personali che forniscono nel loro profilo utente. Tutti gli utenti possono vedere, modificare o eliminare le loro informazioni personali in qualsiasi momento (eccetto il loro nome utente che non possono cambiare). Gli amministratori del sito web possono anche vedere e modificare queste informazioni.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Quali diritti hai sui tuoi dati<\/h2>\n<!-- \/wp:heading -->\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Se hai un account su questo sito, o hai lasciato commenti, puoi richiedere di ricevere un file esportato dal sito con i dati personali che abbiamo su di te, compresi i dati che ci hai fornito. Puoi anche richiedere che cancelliamo tutti i dati personali che ti riguardano. Questo non include i dati che siamo obbligati a conservare per scopi amministrativi, legali o di sicurezza.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Dove i tuoi dati sono inviati<\/h2>\n<!-- \/wp:heading -->\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>I commenti dei visitatori possono essere controllati attraverso un servizio di rilevamento automatico dello spam.<\/p>\n<!-- \/wp:paragraph -->\n","_et_gb_content_width":"","footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/oceanoblunonsolointimo.it\/index.php\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oceanoblunonsolointimo.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oceanoblunonsolointimo.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oceanoblunonsolointimo.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oceanoblunonsolointimo.it\/index.php\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":3,"href":"https:\/\/oceanoblunonsolointimo.it\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":524,"href":"https:\/\/oceanoblunonsolointimo.it\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions\/524"}],"wp:attachment":[{"href":"https:\/\/oceanoblunonsolointimo.it\/index.php\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}